{"id":51479,"date":"2023-05-04T09:56:24","date_gmt":"2023-05-04T07:56:24","guid":{"rendered":"https:\/\/franchisingbelgium.be\/?post_type=franchises&#038;p=51479"},"modified":"2024-10-03T14:28:30","modified_gmt":"2024-10-03T12:28:30","slug":"jumbo","status":"publish","type":"franchises","link":"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/","title":{"rendered":"Jumbo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"single-franchises.blade.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"tags":[258,262],"class_list":["post-51479","franchises","type-franchises","status-publish","hentry","tag-20-000-e-50-000-e","tag-300-000-e-500-000e","secteurs_categories-voedingssector","secteurs_categories-supermarkt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jumbo Franchise - Franchising Belgium<\/title>\n<meta name=\"description\" content=\"Wilt u franchisenemer worden ? Bezoek de website Franchising Belgium en verneem meer over de mogelijkheden van het franchiseconcept van Yves Rocher.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jumbo Franchise - Franchising Belgium\" \/>\n<meta property=\"og:description\" content=\"Wilt u franchisenemer worden ? Bezoek de website Franchising Belgium en verneem meer over de mogelijkheden van het franchiseconcept van Yves Rocher.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/\" \/>\n<meta property=\"og:site_name\" content=\"Franchising Belgium\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T12:28:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/franchises\\\/jumbo\\\/\",\"url\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/franchises\\\/jumbo\\\/\",\"name\":\"Jumbo Franchise - Franchising Belgium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/#website\"},\"datePublished\":\"2023-05-04T07:56:24+00:00\",\"dateModified\":\"2024-10-03T12:28:30+00:00\",\"description\":\"Wilt u franchisenemer worden ? Bezoek de website Franchising Belgium en verneem meer over de mogelijkheden van het franchiseconcept van Yves Rocher.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/franchises\\\/jumbo\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/franchises\\\/jumbo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/franchises\\\/jumbo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Franchises\",\"item\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/franchises\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jumbo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/\",\"name\":\"Franchising Belgium\",\"description\":\"Le site o\u00f9 franchises et franchiseurs se rencontrent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/franchisingbelgium.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jumbo Franchise - Franchising Belgium","description":"Wilt u franchisenemer worden ? Bezoek de website Franchising Belgium en verneem meer over de mogelijkheden van het franchiseconcept van Yves Rocher.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/","og_locale":"nl_NL","og_type":"article","og_title":"Jumbo Franchise - Franchising Belgium","og_description":"Wilt u franchisenemer worden ? Bezoek de website Franchising Belgium en verneem meer over de mogelijkheden van het franchiseconcept van Yves Rocher.","og_url":"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/","og_site_name":"Franchising Belgium","article_modified_time":"2024-10-03T12:28:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/","url":"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/","name":"Jumbo Franchise - Franchising Belgium","isPartOf":{"@id":"https:\/\/franchisingbelgium.be\/nl\/#website"},"datePublished":"2023-05-04T07:56:24+00:00","dateModified":"2024-10-03T12:28:30+00:00","description":"Wilt u franchisenemer worden ? Bezoek de website Franchising Belgium en verneem meer over de mogelijkheden van het franchiseconcept van Yves Rocher.","breadcrumb":{"@id":"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/franchisingbelgium.be\/nl\/franchises\/jumbo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Franchises","item":"https:\/\/franchisingbelgium.be\/nl\/franchises\/"},{"@type":"ListItem","position":2,"name":"Jumbo"}]},{"@type":"WebSite","@id":"https:\/\/franchisingbelgium.be\/nl\/#website","url":"https:\/\/franchisingbelgium.be\/nl\/","name":"Franchising Belgium","description":"Le site o\u00f9 franchises et franchiseurs se rencontrent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franchisingbelgium.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/franchisingbelgium.be\/nl\/wp-json\/wp\/v2\/franchises\/51479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franchisingbelgium.be\/nl\/wp-json\/wp\/v2\/franchises"}],"about":[{"href":"https:\/\/franchisingbelgium.be\/nl\/wp-json\/wp\/v2\/types\/franchises"}],"version-history":[{"count":21,"href":"https:\/\/franchisingbelgium.be\/nl\/wp-json\/wp\/v2\/franchises\/51479\/revisions"}],"predecessor-version":[{"id":54360,"href":"https:\/\/franchisingbelgium.be\/nl\/wp-json\/wp\/v2\/franchises\/51479\/revisions\/54360"}],"wp:attachment":[{"href":"https:\/\/franchisingbelgium.be\/nl\/wp-json\/wp\/v2\/media?parent=51479"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franchisingbelgium.be\/nl\/wp-json\/wp\/v2\/tags?post=51479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}